{"id":2115,"date":"2019-01-13T17:25:42","date_gmt":"2019-01-13T15:25:42","guid":{"rendered":"http:\/\/cgt-cfa.com\/WordPress\/wp-content\/uploads\/2019\/01\/deces-colombe.jpg"},"modified":"2019-01-13T17:25:42","modified_gmt":"2019-01-13T15:25:42","slug":"deces-colombe","status":"inherit","type":"attachment","link":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/","title":{"rendered":"deces-colombe"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-2115","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La CGT des CFA BTP | .\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"deces-colombe | La CGT des CFA BTP\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-01-13T15:25:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-01-13T15:25:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"deces-colombe | La CGT des CFA BTP\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/danslescfa\\\/deces-de-jacques-reviriego\\\/attachment\\\/deces-colombe\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/danslescfa\\\/deces-de-jacques-reviriego\\\/attachment\\\/deces-colombe\\\/#listItem\",\"name\":\"deces-colombe\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/danslescfa\\\/deces-de-jacques-reviriego\\\/attachment\\\/deces-colombe\\\/#listItem\",\"position\":2,\"name\":\"deces-colombe\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress#listItem\",\"name\":\"Accueil\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/danslescfa\\\/deces-de-jacques-reviriego\\\/attachment\\\/deces-colombe\\\/#itempage\",\"url\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/danslescfa\\\/deces-de-jacques-reviriego\\\/attachment\\\/deces-colombe\\\/\",\"name\":\"deces-colombe | La CGT des CFA BTP\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/danslescfa\\\/deces-de-jacques-reviriego\\\/attachment\\\/deces-colombe\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2019-01-13T17:25:42+02:00\",\"dateModified\":\"2019-01-13T17:25:42+02:00\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/#organization\",\"name\":\"la cgt des CFA b\\u00e2timent et BTP\",\"description\":\".\",\"url\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/author\\\/admin\\\/#author\",\"url\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/danslescfa\\\/deces-de-jacques-reviriego\\\/attachment\\\/deces-colombe\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fea039e1b99ec1a900f238342bef4cbbca39ce511fb6d8d5cffc08786f0f22f?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/#website\",\"url\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/\",\"name\":\"la cgt des CFA b\\u00e2timent et BTP\",\"description\":\".\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"http:\\\/\\\/cgt-cfa.com\\\/WordPress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"deces-colombe | La CGT des CFA BTP","description":"","canonical_url":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/cgt-cfa.com\/WordPress#listItem","position":1,"name":"Accueil","item":"http:\/\/cgt-cfa.com\/WordPress","nextItem":{"@type":"ListItem","@id":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/#listItem","name":"deces-colombe"}},{"@type":"ListItem","@id":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/#listItem","position":2,"name":"deces-colombe","previousItem":{"@type":"ListItem","@id":"http:\/\/cgt-cfa.com\/WordPress#listItem","name":"Accueil"}}]},{"@type":"ItemPage","@id":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/#itempage","url":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/","name":"deces-colombe | La CGT des CFA BTP","inLanguage":"fr-FR","isPartOf":{"@id":"http:\/\/cgt-cfa.com\/WordPress\/#website"},"breadcrumb":{"@id":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/#breadcrumblist"},"author":{"@id":"http:\/\/cgt-cfa.com\/WordPress\/author\/admin\/#author"},"creator":{"@id":"http:\/\/cgt-cfa.com\/WordPress\/author\/admin\/#author"},"datePublished":"2019-01-13T17:25:42+02:00","dateModified":"2019-01-13T17:25:42+02:00"},{"@type":"Organization","@id":"http:\/\/cgt-cfa.com\/WordPress\/#organization","name":"la cgt des CFA b\u00e2timent et BTP","description":".","url":"http:\/\/cgt-cfa.com\/WordPress\/"},{"@type":"Person","@id":"http:\/\/cgt-cfa.com\/WordPress\/author\/admin\/#author","url":"http:\/\/cgt-cfa.com\/WordPress\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/9fea039e1b99ec1a900f238342bef4cbbca39ce511fb6d8d5cffc08786f0f22f?s=96&d=blank&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebSite","@id":"http:\/\/cgt-cfa.com\/WordPress\/#website","url":"http:\/\/cgt-cfa.com\/WordPress\/","name":"la cgt des CFA b\u00e2timent et BTP","description":".","inLanguage":"fr-FR","publisher":{"@id":"http:\/\/cgt-cfa.com\/WordPress\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"La CGT des CFA BTP | .","og:type":"article","og:title":"deces-colombe | La CGT des CFA BTP","og:url":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/","article:published_time":"2019-01-13T15:25:42+00:00","article:modified_time":"2019-01-13T15:25:42+00:00","twitter:card":"summary","twitter:title":"deces-colombe | La CGT des CFA BTP"},"aioseo_meta_data":{"post_id":"2115","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-23 09:58:40","updated":"2025-06-04 02:41:24","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/cgt-cfa.com\/WordPress\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tdeces-colombe\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"http:\/\/cgt-cfa.com\/WordPress"},{"label":"deces-colombe","link":"http:\/\/cgt-cfa.com\/WordPress\/danslescfa\/deces-de-jacques-reviriego\/attachment\/deces-colombe\/"}],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/cgt-cfa.com\/WordPress\/wp-content\/uploads\/2019\/01\/deces-colombe.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"257\" height=\"300\" src=\"http:\/\/cgt-cfa.com\/WordPress\/wp-content\/uploads\/2019\/01\/deces-colombe-257x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/cgt-cfa.com\/WordPress\/wp-content\/uploads\/2019\/01\/deces-colombe-257x300.jpg 257w, http:\/\/cgt-cfa.com\/WordPress\/wp-content\/uploads\/2019\/01\/deces-colombe.jpg 600w\" sizes=\"auto, (max-width: 257px) 100vw, 257px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":700,"file":"2019\/01\/deces-colombe.jpg","sizes":{"thumbnail":{"file":"deces-colombe-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/cgt-cfa.com\/WordPress\/wp-content\/uploads\/2019\/01\/deces-colombe-150x150.jpg"},"medium":{"file":"deces-colombe-257x300.jpg","width":257,"height":300,"mime_type":"image\/jpeg","source_url":"http:\/\/cgt-cfa.com\/WordPress\/wp-content\/uploads\/2019\/01\/deces-colombe-257x300.jpg"},"full":{"file":"deces-colombe.jpg","width":600,"height":700,"mime_type":"image\/jpeg","source_url":"http:\/\/cgt-cfa.com\/WordPress\/wp-content\/uploads\/2019\/01\/deces-colombe.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":2112,"source_url":"http:\/\/cgt-cfa.com\/WordPress\/wp-content\/uploads\/2019\/01\/deces-colombe.jpg","_links":{"self":[{"href":"http:\/\/cgt-cfa.com\/WordPress\/wp-json\/wp\/v2\/media\/2115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cgt-cfa.com\/WordPress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/cgt-cfa.com\/WordPress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/cgt-cfa.com\/WordPress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cgt-cfa.com\/WordPress\/wp-json\/wp\/v2\/comments?post=2115"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2112,"href":"http:\/\/cgt-cfa.com\/WordPress\/wp-json\/wp\/v2\/posts\/2112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}